{"id":67378,"date":"2024-09-11T04:54:12","date_gmt":"2024-09-11T02:54:12","guid":{"rendered":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg"},"modified":"2024-09-11T04:54:13","modified_gmt":"2024-09-11T02:54:13","slug":"previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano","status":"inherit","type":"attachment","link":"https:\/\/www.ledizioni.it\/en\/?attachment_id=67378","title":{"rendered":"Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#8217;artigianato artistico tradizionale veneziano"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-67378","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#039;artigianato artistico tradizionale veneziano -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#039;artigianato artistico tradizionale veneziano -\" \/>\n<meta property=\"og:description\" content=\"Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#039;artigianato artistico tradizionale veneziano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Ledizioni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T02:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1390\" \/>\n\t<meta property=\"og:image:height\" content=\"1859\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ledizioni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg\",\"name\":\"Copertina del libro Previsioni occupazionali e prospettive nel settore dell'artigianato artistico tradizionale veneziano -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\"},\"datePublished\":\"2024-09-11T02:54:12+00:00\",\"dateModified\":\"2024-09-11T02:54:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"PREVISIONI OCCUPAZIONALI E PROSPETTIVE NEL SETTORE DELL&#8217;ARTIGIANATO ARTISTICO TRADIZIONALE VENEZIANO\",\"item\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#8217;artigianato artistico tradizionale veneziano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"name\":\"Ledizioni\",\"description\":\"The Innovative LediPublishing Company - Casa Editrice Universitaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ledizioni.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\",\"name\":\"Ledizioni\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"width\":354,\"height\":87,\"caption\":\"Ledizioni\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Ledizioni-LediPublishing\\\/109120559173329\",\"https:\\\/\\\/x.com\\\/ledizioni\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Copertina del libro Previsioni occupazionali e prospettive nel settore dell'artigianato artistico tradizionale veneziano -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","og_locale":"en_GB","og_type":"article","og_title":"Copertina del libro Previsioni occupazionali e prospettive nel settore dell'artigianato artistico tradizionale veneziano -","og_description":"Copertina del libro Previsioni occupazionali e prospettive nel settore dell'artigianato artistico tradizionale veneziano","og_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","og_site_name":"Ledizioni","article_publisher":"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","article_modified_time":"2024-09-11T02:54:13+00:00","og_image":[{"width":1390,"height":1859,"url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ledizioni","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","name":"Copertina del libro Previsioni occupazionali e prospettive nel settore dell'artigianato artistico tradizionale veneziano -","isPartOf":{"@id":"https:\/\/www.ledizioni.it\/#website"},"datePublished":"2024-09-11T02:54:12+00:00","dateModified":"2024-09-11T02:54:13+00:00","breadcrumb":{"@id":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"PREVISIONI OCCUPAZIONALI E PROSPETTIVE NEL SETTORE DELL&#8217;ARTIGIANATO ARTISTICO TRADIZIONALE VENEZIANO","item":"https:\/\/www.ledizioni.it\/prodotto\/previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano\/"},{"@type":"ListItem","position":2,"name":"Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#8217;artigianato artistico tradizionale veneziano"}]},{"@type":"WebSite","@id":"https:\/\/www.ledizioni.it\/#website","url":"https:\/\/www.ledizioni.it\/","name":"Ledizioni","description":"The Innovative LediPublishing Company - Casa Editrice Universitaria","publisher":{"@id":"https:\/\/www.ledizioni.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ledizioni.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.ledizioni.it\/#organization","name":"Ledizioni","url":"https:\/\/www.ledizioni.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","width":354,"height":87,"caption":"Ledizioni"},"image":{"@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","https:\/\/x.com\/ledizioni"]}]}},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"224\" height=\"300\" src=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-224x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#039;artigianato artistico tradizionale veneziano\" srcset=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-224x300.jpg 224w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-598x800.jpg 598w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-187x250.jpg 187w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-768x1027.jpg 768w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-1148x1536.jpg 1148w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-9x12.jpg 9w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-600x802.jpg 600w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-300x401.jpg 300w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-400x535.jpg 400w, https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg 1390w\" sizes=\"(max-width: 224px) 100vw, 224px\" \/><\/a><\/p>\n<p>Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#8217;artigianato artistico tradizionale veneziano<\/p>\n"},"caption":{"rendered":"<p>Copertina del libro Previsioni occupazionali e prospettive nel settore dell&#8217;artigianato artistico tradizionale veneziano<\/p>\n"},"alt_text":"Copertina del libro Previsioni occupazionali e prospettive nel settore dell'artigianato artistico tradizionale veneziano","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1390,"height":1859,"file":"2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","filesize":421193,"sizes":{"medium":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-224x300.jpg","width":224,"height":300,"filesize":19156,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-224x300.jpg"},"large":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-598x800.jpg","width":598,"height":800,"filesize":87264,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-598x800.jpg"},"thumbnail":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-187x250.jpg","width":187,"height":250,"filesize":15027,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-187x250.jpg"},"medium_large":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-768x1027.jpg","width":768,"height":1027,"filesize":126915,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-768x1027.jpg"},"1536x1536":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-1148x1536.jpg","width":1148,"height":1536,"filesize":225129,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-1148x1536.jpg"},"trp-custom-language-flag":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-9x12.jpg","width":9,"height":12,"filesize":733,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-9x12.jpg"},"woodmart_shop_catalog_x2":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-600x802.jpg","width":600,"height":802,"filesize":86996,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-600x802.jpg"},"woocommerce_thumbnail":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-300x401.jpg","width":300,"height":401,"filesize":31706,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-300x401.jpg"},"woocommerce_single":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-400x535.jpg","width":400,"height":535,"filesize":48569,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-400x535.jpg"},"woocommerce_gallery_thumbnail":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-300x401.jpg","width":300,"height":401,"filesize":31706,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano-300x401.jpg"},"full":{"file":"Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","width":1390,"height":1859,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":67377,"source_url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2024\/09\/Previsioni-occupazionali-e-prospettive-nel-settore-dellartigianato-artistico-tradizionale-veneziano.jpg","_links":{"self":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media\/67378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/comments?post=67378"}]}}