{"id":27391,"date":"2020-02-27T16:02:38","date_gmt":"2020-02-27T14:02:38","guid":{"rendered":"https:\/\/www.ledizioni.it\/?post_type=product&#038;p=27391"},"modified":"2021-06-09T17:01:37","modified_gmt":"2021-06-09T15:01:37","slug":"impara-a-usare-il-brainwaive-entrainment","status":"publish","type":"product","link":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/","title":{"rendered":"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT"},"content":{"rendered":"<p style=\"text-align: justify;\">Questo libro ti introduce al mondo del Brainwave Entrainment, cio\u00e8 la sincronizzazione delle tue onde cerebrali con quelle di una specifica frequenza sonora. Questo metodo, che ha radici antichissime, ha lo scopo di sintonizzare la mente su onde diverse e con differenti caratteristiche e finalit\u00e0.<br \/>\nA seconda delle onde usate, puoi indurre un profondo stato di rilassamento, puoi risvegliare in te il potere dell\u2019autoguarigione, puoi aprire la strada del benessere psicofisico e della connessione spirituale. L\u2019attivazione di determinate onde cerebrali ti permette di attivare specifici stati mentali, nuovi pensieri e quindi manifestare ci\u00f2 che desideri.<br \/>\nImparerai come sintonizzare il tuo cervello su una o pi\u00f9 specifiche frequenze per cambiare il tuo stato mentale e creare la tua perfetta realt\u00e0.<br \/>\nIn conclusione, potrai approfondire il tema dell\u2019ipnosi, dell\u2019autoipnosi e dei suoni binaurali e scoprirai come la conoscenza e l\u2019utilizzo di questi strumenti di crescita personale possano aiutarti a portare benefici in ogni ambito della tua vita: dal dimagrimento al miglioramento della concentrazione; dall\u2019aumento dell\u2019autostima allo sviluppo della creativit\u00e0, dalla sconfitta di dipendenze alla gestione delle fobie.<\/p>\n<p style=\"text-align: justify;\"><strong>DATI BIBLIOGRAFICI<\/strong><br \/>\nAutore: Eric Edwards<br \/>\nEditore: Ledizioni<br \/>\nPubblicato in: 2019<br \/>\nCollana: <a href=\"https:\/\/www.ledizioni.it\/en\/product-category\/varia\/crescita-personale\/\">Personal growth<\/a><br \/>\nFormato: brossura, 117 p.<br \/>\nISBN cartaceo: 9788855260206<br \/>\nPrezzo: 9.90\u20ac<\/p>","protected":false},"excerpt":{"rendered":"<p>Questo libro ti introduce al mondo del Brainwave Entrainment, cio\u00e8 la sincronizzazione delle tue onde cerebrali con quelle di una<\/p>","protected":false},"featured_media":27392,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1467],"product_tag":[1754,2110],"class_list":["post-27391","product","type-product","status-publish","has-post-thumbnail","product_cat-crescita-personale","product_tag-scienza-della-mente","product_tag-sviluppo-personale","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMPARA A USARE IL BRAINWAIVE ENTRAINMENT -<\/title>\n<meta name=\"description\" content=\"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT -\" \/>\n<meta property=\"og:description\" content=\"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/\" \/>\n<meta property=\"og:site_name\" content=\"Ledizioni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T15:01:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2020\/02\/brainwaive_3D.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ledizioni\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/\",\"name\":\"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/brainwaive_3D.jpg\",\"datePublished\":\"2020-02-27T14:02:38+00:00\",\"dateModified\":\"2021-06-09T15:01:37+00:00\",\"description\":\"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/brainwaive_3D.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/brainwaive_3D.jpg\",\"width\":400,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product\\\/impara-a-usare-il-brainwaive-entrainment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.ledizioni.it\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"name\":\"Ledizioni\",\"description\":\"The Innovative LediPublishing Company - Casa Editrice Universitaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ledizioni.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\",\"name\":\"Ledizioni\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"width\":354,\"height\":87,\"caption\":\"Ledizioni\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Ledizioni-LediPublishing\\\/109120559173329\",\"https:\\\/\\\/x.com\\\/ledizioni\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT -","description":"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/","og_locale":"en_GB","og_type":"article","og_title":"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT -","og_description":"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.","og_url":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/","og_site_name":"Ledizioni","article_publisher":"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","article_modified_time":"2021-06-09T15:01:37+00:00","og_image":[{"width":400,"height":533,"url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2020\/02\/brainwaive_3D.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ledizioni","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/","url":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/","name":"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT -","isPartOf":{"@id":"https:\/\/www.ledizioni.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/#primaryimage"},"image":{"@id":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2020\/02\/brainwaive_3D.jpg","datePublished":"2020-02-27T14:02:38+00:00","dateModified":"2021-06-09T15:01:37+00:00","description":"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.","breadcrumb":{"@id":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/#primaryimage","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2020\/02\/brainwaive_3D.jpg","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2020\/02\/brainwaive_3D.jpg","width":400,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.ledizioni.it\/en\/product\/impara-a-usare-il-brainwaive-entrainment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/www.ledizioni.it\/shop-2\/"},{"@type":"ListItem","position":2,"name":"IMPARA A USARE IL BRAINWAIVE ENTRAINMENT"}]},{"@type":"WebSite","@id":"https:\/\/www.ledizioni.it\/#website","url":"https:\/\/www.ledizioni.it\/","name":"Ledizioni","description":"The Innovative LediPublishing Company - Casa Editrice Universitaria","publisher":{"@id":"https:\/\/www.ledizioni.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ledizioni.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.ledizioni.it\/#organization","name":"Ledizioni","url":"https:\/\/www.ledizioni.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","width":354,"height":87,"caption":"Ledizioni"},"image":{"@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","https:\/\/x.com\/ledizioni"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product\/27391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/comments?post=27391"}],"version-history":[{"count":0,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product\/27391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media\/27392"}],"wp:attachment":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media?parent=27391"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_brand?post=27391"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_cat?post=27391"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_tag?post=27391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}