{"id":6323,"date":"2013-06-24T19:12:02","date_gmt":"2013-06-24T19:12:02","guid":{"rendered":"http:\/\/www.ledizioni.it\/stag\/?post_type=product&#038;p=6323"},"modified":"2019-10-02T16:57:40","modified_gmt":"2019-10-02T14:57:40","slug":"paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics","status":"publish","type":"product","link":"https:\/\/www.ledizioni.it\/en\/product\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/","title":{"rendered":"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS"},"content":{"rendered":"<p style=\"text-align: justify;\">[amazon_link asins=&#8217;8895994132&#8242; template=&#8217;PriceLink1&#8242; store=&#8217;ledizioni-21&#8242; marketplace=&#8217;IT&#8217; link_id=&#8217;6819a589-e1a3-11e8-ac07-67413c9b1b92&#8242;]<\/p>\n<p style=\"text-align: justify;\">Pubblicato a Londra nel 1826 sulla \u00abRetrospective Review\u00bb, in traduzione inglese e con il titolo <em>On the Antiquarians and Critics of Italian History<\/em>, l\u2019articolo <em>Antiquarj e Critici di materiali storici in Italia per servire alla storia Europea nel medio Evo<\/em> \u00e8 uno tra gli scritti pi\u00f9 belli e importanti del periodo londinese di Ugo Foscolo.<br \/>\nL\u2019autore vi esalta l\u2019opera dei grandi storici, eruditi e antiquari italiani del Settecento \u2013 Zeno, Maffei, Bianchini, Magliabechi, Muratori \u2013 e, a fronte della loro taccia di \u00abnojosi\u00bb, non esita a riconoscerli come autentici \u00abgenii\u00bb, quantunque \u00abtardissimi e freddi\u00bb. Ne risulta un intervento che mira a incidere nel dibattito europeo ottocentesco sull\u2019\u00abarte storica\u00bb: la pazienza, la precisione e lo scrupolo degli antiquari \u00abgiganti\u00bb \u00e8 proposta da Foscolo come il miglior antidoto da un lato contro gli eccessi speculativi della storiografia moderna e dall\u2019altro contro i pericoli del pregiudizio e della faziosit\u00e0, che impediscono una rigorosa ricostruzione degli eventi e della loro successione.<br \/>\nSecondo una prospettiva filologica innovativa, che mira a mettere in luce il carattere provvisorio delle redazioni \u201cdi lavoro\u201d approntate da Foscolo per i traduttori e intende avviare un complessivo ripensamento dei criteri ecdotici con cui sono stati pubblicati molti dei suoi scritti \u201cinglesi\u201d, in questa edizione critica il testo del manoscritto \u00e8 presentato per la prima volta accanto alla sua traduzione, apparsa a stampa sulla \u00abRetrospective Review\u00bb, ed \u00e8 preceduto da un\u2019ampia Introduzione, che illustra i contenuti del saggio foscoliano e chiarisce modalit\u00e0 e circostanze della sua stesura.<\/p>\n<p style=\"text-align: justify;\">Trovate a <a href=\"http:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2014\/04\/recensione.pdf\" target=\"_blank\" rel=\"noopener\">questo link<\/a> una recensione dell&#8217;opera, scritta da Gabriele Fantini per <em>La Rassegna della Letteratura Italiana<\/em> (Anno 117, Serie IX).<\/p>\n<h3><strong><span style=\"color: #000000;\">DATI BIBLI<\/span><span style=\"color: #000000;\">OGRAFICI<\/span><\/strong><\/h3>\n<p>Autori: Paolo Borsa<br \/>\nEditore: Ledizioni<br \/>\nCollana: <a title=\"Editoria Presente e futuro\" href=\"http:\/\/www.ledizioni.it\/en\/sito\/collane\/letteratura\/264-2\/\">La Ragione Critica<\/a><br \/>\nFormato: Brossura<br \/>\nPubblicato in: Ottobre 2012<br \/>\nISBN:\u00a09788895994130 (cartaceo)<br \/>\nPrezzo cartaceo: 22,00 \u20ac<\/p>\n<p><a href=\"http:\/\/www.mondadoristore.it\/Ugo-Foscolo.-Antiquarj-e-Borsa-Paolo\/eab\/selfespress\/9788895994130\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone size-full wp-image-14398 aligncenter\" src=\"http:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2012\/06\/red-podok.jpg\" alt=\"Pod MondadoriStore\" width=\"200\" height=\"82\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.torrossa.com\/it\/resources\/an\/3052359\"><img decoding=\"async\" class=\"aligncenter wp-image-23912\" src=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2019\/07\/torrossa_web-150x80.jpg\" alt=\"\" width=\"200\" height=\"60\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>[amazon_link asins=&#8217;8895994132&#8242; template=&#8217;PriceLink1&#8242; store=&#8217;ledizioni-21&#8242; marketplace=&#8217;IT&#8217; link_id=&#8217;6819a589-e1a3-11e8-ac07-67413c9b1b92&#8242;] Pubblicato a Londra nel 1826 sulla \u00abRetrospective Review\u00bb, in traduzione inglese e con il<\/p>","protected":false},"featured_media":6324,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[370],"product_tag":[],"class_list":{"0":"post-6323","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-la-ragione-critica","7":"pa_formato-cartaceo","8":"pa_lingua-inglese","9":"pa_lingua-italiano","11":"first","12":"instock","13":"featured","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS -<\/title>\n<meta name=\"description\" content=\"Edizione critica con versione italiana e inglese di un articolo che \u00e8 tra gli scritti pi\u00f9 belli e importanti del periodo londinese di Foscolo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ledizioni.it\/en\/product\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS -\" \/>\n<meta property=\"og:description\" content=\"Edizione critica con versione italiana e inglese di un articolo che \u00e8 tra gli scritti pi\u00f9 belli e importanti del periodo londinese di Foscolo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ledizioni.it\/en\/product\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/\" \/>\n<meta property=\"og:site_name\" content=\"Ledizioni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-02T14:57:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/3dsito-762x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ledizioni\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/\",\"name\":\"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/3dsito-762x1024.jpg\",\"datePublished\":\"2013-06-24T19:12:02+00:00\",\"dateModified\":\"2019-10-02T14:57:40+00:00\",\"description\":\"Edizione critica con versione italiana e inglese di un articolo che \u00e8 tra gli scritti pi\u00f9 belli e importanti del periodo londinese di Foscolo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/3dsito-762x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/3dsito-762x1024.jpg\",\"width\":762,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.ledizioni.it\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"name\":\"Ledizioni\",\"description\":\"The Innovative LediPublishing Company - Casa Editrice Universitaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ledizioni.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\",\"name\":\"Ledizioni\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"width\":354,\"height\":87,\"caption\":\"Ledizioni\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Ledizioni-LediPublishing\\\/109120559173329\",\"https:\\\/\\\/x.com\\\/ledizioni\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS -","description":"Edizione critica con versione italiana e inglese di un articolo che \u00e8 tra gli scritti pi\u00f9 belli e importanti del periodo londinese di Foscolo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ledizioni.it\/en\/product\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/","og_locale":"en_GB","og_type":"article","og_title":"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS -","og_description":"Edizione critica con versione italiana e inglese di un articolo che \u00e8 tra gli scritti pi\u00f9 belli e importanti del periodo londinese di Foscolo.","og_url":"https:\/\/www.ledizioni.it\/en\/product\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/","og_site_name":"Ledizioni","article_publisher":"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","article_modified_time":"2019-10-02T14:57:40+00:00","og_image":[{"width":762,"height":1024,"url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/3dsito-762x1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ledizioni","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/","url":"https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/","name":"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS -","isPartOf":{"@id":"https:\/\/www.ledizioni.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/#primaryimage"},"image":{"@id":"https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/3dsito-762x1024.jpg","datePublished":"2013-06-24T19:12:02+00:00","dateModified":"2019-10-02T14:57:40+00:00","description":"Edizione critica con versione italiana e inglese di un articolo che \u00e8 tra gli scritti pi\u00f9 belli e importanti del periodo londinese di Foscolo.","breadcrumb":{"@id":"https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/#primaryimage","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/3dsito-762x1024.jpg","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/3dsito-762x1024.jpg","width":762,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.ledizioni.it\/prodotto\/paolo-borsa-ugo-foscolo-antiquarj-e-critici-on-the-antiquarians-and-critics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/www.ledizioni.it\/shop-2\/"},{"@type":"ListItem","position":2,"name":"UGO FOSCOLO. ANTIQUARJ E CRITICI-ON THE ANTIQUARIANS AND CRITICS"}]},{"@type":"WebSite","@id":"https:\/\/www.ledizioni.it\/#website","url":"https:\/\/www.ledizioni.it\/","name":"Ledizioni","description":"The Innovative LediPublishing Company - Casa Editrice Universitaria","publisher":{"@id":"https:\/\/www.ledizioni.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ledizioni.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.ledizioni.it\/#organization","name":"Ledizioni","url":"https:\/\/www.ledizioni.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","width":354,"height":87,"caption":"Ledizioni"},"image":{"@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","https:\/\/x.com\/ledizioni"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product\/6323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/comments?post=6323"}],"version-history":[{"count":1,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product\/6323\/revisions"}],"predecessor-version":[{"id":8418,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product\/6323\/revisions\/8418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media\/6324"}],"wp:attachment":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media?parent=6323"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_brand?post=6323"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_cat?post=6323"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_tag?post=6323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}