{"id":6799,"date":"2011-11-23T13:28:39","date_gmt":"2011-11-23T11:28:39","guid":{"rendered":"http:\/\/www.ledizioni.it\/stag\/?post_type=product&#038;p=6799"},"modified":"2021-06-11T16:21:26","modified_gmt":"2021-06-11T14:21:26","slug":"connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione","status":"publish","type":"product","link":"https:\/\/www.ledizioni.it\/en\/product\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/","title":{"rendered":"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione"},"content":{"rendered":"<p><em>SIEL 2011 \u2013 Atti VIII Congresso Nazionale della Societ\u00e0 Italiana di e-Learning.<\/em><\/p>\n<p>L\u2019 VIII Congresso Nazionale della Societ\u00e0 Italiana di e-Learning (Reggio Emilia, 14-16 Settembre 2011) si \u00e8 posto l\u2019obiettivo di provare a definire quali potranno essere gli scenari di evoluzione della applicazione e utilizzo delle tecnologie dell\u2019informazione e della comunicazione ai processi della formazione, dell\u2019 educazione, dell\u2019editoria e dell\u2019informazione. Uno sguardo, un ponte, verso il futuro o, meglio, verso i futuri possibili.<\/p>","protected":false},"excerpt":{"rendered":"<p>SIEL 2011 \u2013 Atti VIII Congresso Nazionale della Societ\u00e0 Italiana di e-Learning. L\u2019 VIII Congresso Nazionale della Societ\u00e0 Italiana di<\/p>","protected":false},"featured_media":6801,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1042],"product_tag":[1335,805,592,1310],"class_list":["post-6799","product","type-product","status-publish","has-post-thumbnail","product_cat-politica","product_tag-comunicazione","product_tag-digitale-2","product_tag-elearning","product_tag-formazione","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione -<\/title>\n<meta name=\"description\" content=\"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ledizioni.it\/en\/product\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione -\" \/>\n<meta property=\"og:description\" content=\"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ledizioni.it\/en\/product\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ledizioni\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-11T14:21:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/admin-ajax-210.png\" \/>\n\t<meta property=\"og:image:width\" content=\"211\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ledizioni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/\",\"name\":\"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/admin-ajax-210.png\",\"datePublished\":\"2011-11-23T11:28:39+00:00\",\"dateModified\":\"2021-06-11T14:21:26+00:00\",\"description\":\"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/admin-ajax-210.png\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2013\\\/07\\\/admin-ajax-210.png\",\"width\":211,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/prodotto\\\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.ledizioni.it\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"name\":\"Ledizioni\",\"description\":\"The Innovative LediPublishing Company - Casa Editrice Universitaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ledizioni.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\",\"name\":\"Ledizioni\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"width\":354,\"height\":87,\"caption\":\"Ledizioni\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Ledizioni-LediPublishing\\\/109120559173329\",\"https:\\\/\\\/x.com\\\/ledizioni\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione -","description":"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ledizioni.it\/en\/product\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/","og_locale":"en_GB","og_type":"article","og_title":"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione -","og_description":"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.","og_url":"https:\/\/www.ledizioni.it\/en\/product\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/","og_site_name":"Ledizioni","article_publisher":"https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","article_modified_time":"2021-06-11T14:21:26+00:00","og_image":[{"width":211,"height":300,"url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/admin-ajax-210.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ledizioni","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/","url":"https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/","name":"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione -","isPartOf":{"@id":"https:\/\/www.ledizioni.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/#primaryimage"},"image":{"@id":"https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/admin-ajax-210.png","datePublished":"2011-11-23T11:28:39+00:00","dateModified":"2021-06-11T14:21:26+00:00","description":"Ledizioni - Innovative Publishing. Casa editrice universitaria. Open Access. eBook, ePub. Creative Commons.","breadcrumb":{"@id":"https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/#primaryimage","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/admin-ajax-210.png","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2013\/07\/admin-ajax-210.png","width":211,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.ledizioni.it\/prodotto\/connessi-scenari-di-innovazione-nella-formazione-e-nella-comunicazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/www.ledizioni.it\/shop-2\/"},{"@type":"ListItem","position":2,"name":"Connessi! Scenari di Innovazione nella Formazione e nella Comunicazione"}]},{"@type":"WebSite","@id":"https:\/\/www.ledizioni.it\/#website","url":"https:\/\/www.ledizioni.it\/","name":"Ledizioni","description":"The Innovative LediPublishing Company - Casa Editrice Universitaria","publisher":{"@id":"https:\/\/www.ledizioni.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ledizioni.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.ledizioni.it\/#organization","name":"Ledizioni","url":"https:\/\/www.ledizioni.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","width":354,"height":87,"caption":"Ledizioni"},"image":{"@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","https:\/\/x.com\/ledizioni"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product\/6799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/comments?post=6799"}],"version-history":[{"count":0,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product\/6799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media\/6801"}],"wp:attachment":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/media?parent=6799"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_brand?post=6799"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_cat?post=6799"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_tag?post=6799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}