{"id":783,"count":10,"description":"<a href=\"http:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2014\/03\/unipavia.jpg\"><img class=\"wp-image-8293 alignleft\" src=\"http:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2014\/03\/unipavia.jpg\" alt=\"unipavia\" width=\"357\" height=\"154\" \/><\/a>Giunti alla sesta edizione del Master in \u201cImmigrazione, Genere, Modelli Familiari e Strategie di Integrazione\" dell\u2019Universit\u00e0 degli Studi di Pavia, abbiamo deciso di inaugurare una serie di Quaderni sui temi delle migrazioni. Dopo il primo numero, dedicato ai lavori di tesi pi\u00f9 meritevoli degli studenti della IV edizione, i Quaderni si propongono di diventare uno spazio per quanti portano il proprio contributo all\u2019interno del Master che ogni anno si arricchisce della presenza di studiosi, ricercatori e operatori che indagano e affrontano, con il loro lavoro, i tanti aspetti del fenomeno delle mobilit\u00e0 umane e che mostrano in ci\u00f2 particolare sensibilit\u00e0 ai temi di genere.\r\n\r\nIl Master nasce infatti dalla considerazione che troppo spesso la progettazione e la gestione di interventi a favore dell\u2019integrazione degli immigrati non tiene conto delle differenze di genere e della complessit\u00e0 che definisce l\u2019universo dell\u2019immigrazione, sottovalutando l\u2019urgenza di offrire risposte adeguate alle domande che da l\u00ec provengono. Ci\u00f2 \u00e8 una grave omissione per una serie di motivi: perch\u00e9 alle donne debbono essere destinate misure specifiche volte a combattere il doppio rischio di esclusione sociale a cui sono esposte in quanto donne e in quanto migranti; perch\u00e9 l\u2019esperienza dei paesi di pi\u00f9 antica immigrazione conferma la funzione stabilizzante e di mediazione tra sfera pubblica e sfera privata che le donne immigrate svolgono all\u2019interno delle loro famiglie; perch\u00e9 come lavoratrici la maggior parte di loro offre servizi di accudimento e assistenza presso le famiglie italiane , svolgendo anche in questo caso un compito insostituibile; perch\u00e9 quanto pi\u00f9 gli immigrati e le loro famiglie saranno integrati nel tessuto sociale del nostro paese, tanto pi\u00f9 saranno alti i benefici di cui tutti noi, autoctoni e immigrati, potremo godere.\r\n\r\n<strong>Direzione:<\/strong> Anna Rita Calabr\u00f2 - Coordinatore del Master e Direttore del Centro Interdipartimentale di Studi di Genere.\r\n<strong>Comitato scientifico: <\/strong>Anna Rita Calabr\u00f2, Marina Chini, Maria Antonietta Confalonieri, Giovanni Cordini, Silvia Illari, Antonietta Marchi, Caterina Mauri, Antonio Morone, Maria Assunta Zanetti.","link":"https:\/\/www.ledizioni.it\/en\/product-category\/politica\/quaderni-del-master-in-immigrazione\/","name":"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione","slug":"quaderni-del-master-in-immigrazione","taxonomy":"product_cat","parent":1042,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ledizioni.it\/en\/product-category\/politica\/quaderni-del-master-in-immigrazione\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione Archives -\" \/>\n<meta property=\"og:description\" content=\"Giunti alla sesta edizione del Master in \u201cImmigrazione, Genere, Modelli Familiari e Strategie di Integrazione&#8221; dell\u2019Universit\u00e0 degli Studi di Pavia, abbiamo deciso di inaugurare una serie di Quaderni sui temi delle migrazioni. Dopo il primo numero, dedicato ai lavori di tesi pi\u00f9 meritevoli degli studenti della IV edizione, i Quaderni si propongono di diventare uno spazio per quanti portano il proprio contributo all\u2019interno del Master che ogni anno si arricchisce della presenza di studiosi, ricercatori e operatori che indagano e affrontano, con il loro lavoro, i tanti aspetti del fenomeno delle mobilit\u00e0 umane e che mostrano in ci\u00f2 particolare sensibilit\u00e0 ai temi di genere. Il Master nasce infatti dalla considerazione che troppo spesso la progettazione e la gestione di interventi a favore dell\u2019integrazione degli immigrati non tiene conto delle differenze di genere e della complessit\u00e0 che definisce l\u2019universo dell\u2019immigrazione, sottovalutando l\u2019urgenza di offrire risposte adeguate alle domande che da l\u00ec provengono. Ci\u00f2 \u00e8 una grave omissione per una serie di motivi: perch\u00e9 alle donne debbono essere destinate misure specifiche volte a combattere il doppio rischio di esclusione sociale a cui sono esposte in quanto donne e in quanto migranti; perch\u00e9 l\u2019esperienza dei paesi di pi\u00f9 antica immigrazione conferma la funzione stabilizzante e di mediazione tra sfera pubblica e sfera privata che le donne immigrate svolgono all\u2019interno delle loro famiglie; perch\u00e9 come lavoratrici la maggior parte di loro offre servizi di accudimento e assistenza presso le famiglie italiane , svolgendo anche in questo caso un compito insostituibile; perch\u00e9 quanto pi\u00f9 gli immigrati e le loro famiglie saranno integrati nel tessuto sociale del nostro paese, tanto pi\u00f9 saranno alti i benefici di cui tutti noi, autoctoni e immigrati, potremo godere. Direzione: Anna Rita Calabr\u00f2 &#8211; Coordinatore del Master e Direttore del Centro Interdipartimentale di Studi di Genere. Comitato scientifico: Anna Rita Calabr\u00f2, Marina Chini, Maria Antonietta Confalonieri, Giovanni Cordini, Silvia Illari, Antonietta Marchi, Caterina Mauri, Antonio Morone, Maria Assunta Zanetti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ledizioni.it\/en\/product-category\/politica\/quaderni-del-master-in-immigrazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ledizioni\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2014\/03\/unipavia.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ledizioni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/categoria-prodotto\\\/politica\\\/quaderni-del-master-in-immigrazione\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/categoria-prodotto\\\/politica\\\/quaderni-del-master-in-immigrazione\\\/\",\"name\":\"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione Archives -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/categoria-prodotto\\\/politica\\\/quaderni-del-master-in-immigrazione\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/categoria-prodotto\\\/politica\\\/quaderni-del-master-in-immigrazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Attualit\u00e0 e Politica\",\"item\":\"https:\\\/\\\/www.ledizioni.it\\\/en\\\/product-category\\\/politica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#website\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"name\":\"Ledizioni\",\"description\":\"The Innovative LediPublishing Company - Casa Editrice Universitaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ledizioni.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#organization\",\"name\":\"Ledizioni\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ledizioni.it\\\/stag\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/newlogoledizioni500x110_2-1.jpg\",\"width\":354,\"height\":87,\"caption\":\"Ledizioni\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ledizioni.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Ledizioni-LediPublishing\\\/109120559173329\",\"https:\\\/\\\/x.com\\\/ledizioni\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ledizioni.it\/en\/product-category\/politica\/quaderni-del-master-in-immigrazione\/","og_locale":"en_GB","og_type":"article","og_title":"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione Archives -","og_description":"Giunti alla sesta edizione del Master in \u201cImmigrazione, Genere, Modelli Familiari e Strategie di Integrazione&#8221; dell\u2019Universit\u00e0 degli Studi di Pavia, abbiamo deciso di inaugurare una serie di Quaderni sui temi delle migrazioni. Dopo il primo numero, dedicato ai lavori di tesi pi\u00f9 meritevoli degli studenti della IV edizione, i Quaderni si propongono di diventare uno spazio per quanti portano il proprio contributo all\u2019interno del Master che ogni anno si arricchisce della presenza di studiosi, ricercatori e operatori che indagano e affrontano, con il loro lavoro, i tanti aspetti del fenomeno delle mobilit\u00e0 umane e che mostrano in ci\u00f2 particolare sensibilit\u00e0 ai temi di genere. Il Master nasce infatti dalla considerazione che troppo spesso la progettazione e la gestione di interventi a favore dell\u2019integrazione degli immigrati non tiene conto delle differenze di genere e della complessit\u00e0 che definisce l\u2019universo dell\u2019immigrazione, sottovalutando l\u2019urgenza di offrire risposte adeguate alle domande che da l\u00ec provengono. Ci\u00f2 \u00e8 una grave omissione per una serie di motivi: perch\u00e9 alle donne debbono essere destinate misure specifiche volte a combattere il doppio rischio di esclusione sociale a cui sono esposte in quanto donne e in quanto migranti; perch\u00e9 l\u2019esperienza dei paesi di pi\u00f9 antica immigrazione conferma la funzione stabilizzante e di mediazione tra sfera pubblica e sfera privata che le donne immigrate svolgono all\u2019interno delle loro famiglie; perch\u00e9 come lavoratrici la maggior parte di loro offre servizi di accudimento e assistenza presso le famiglie italiane , svolgendo anche in questo caso un compito insostituibile; perch\u00e9 quanto pi\u00f9 gli immigrati e le loro famiglie saranno integrati nel tessuto sociale del nostro paese, tanto pi\u00f9 saranno alti i benefici di cui tutti noi, autoctoni e immigrati, potremo godere. Direzione: Anna Rita Calabr\u00f2 &#8211; Coordinatore del Master e Direttore del Centro Interdipartimentale di Studi di Genere. Comitato scientifico: Anna Rita Calabr\u00f2, Marina Chini, Maria Antonietta Confalonieri, Giovanni Cordini, Silvia Illari, Antonietta Marchi, Caterina Mauri, Antonio Morone, Maria Assunta Zanetti.","og_url":"https:\/\/www.ledizioni.it\/en\/product-category\/politica\/quaderni-del-master-in-immigrazione\/","og_site_name":"Ledizioni","og_image":[{"url":"http:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2014\/03\/unipavia.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@ledizioni","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ledizioni.it\/categoria-prodotto\/politica\/quaderni-del-master-in-immigrazione\/","url":"https:\/\/www.ledizioni.it\/categoria-prodotto\/politica\/quaderni-del-master-in-immigrazione\/","name":"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione Archives -","isPartOf":{"@id":"https:\/\/www.ledizioni.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.ledizioni.it\/categoria-prodotto\/politica\/quaderni-del-master-in-immigrazione\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ledizioni.it\/categoria-prodotto\/politica\/quaderni-del-master-in-immigrazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Attualit\u00e0 e Politica","item":"https:\/\/www.ledizioni.it\/en\/product-category\/politica\/"},{"@type":"ListItem","position":2,"name":"Quaderni del Master in Immigrazione, Genere, Modelli Familiari e Strategie di Integrazione"}]},{"@type":"WebSite","@id":"https:\/\/www.ledizioni.it\/#website","url":"https:\/\/www.ledizioni.it\/","name":"Ledizioni","description":"The Innovative LediPublishing Company - Casa Editrice Universitaria","publisher":{"@id":"https:\/\/www.ledizioni.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ledizioni.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.ledizioni.it\/#organization","name":"Ledizioni","url":"https:\/\/www.ledizioni.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","contentUrl":"https:\/\/www.ledizioni.it\/stag\/wp-content\/uploads\/2023\/10\/newlogoledizioni500x110_2-1.jpg","width":354,"height":87,"caption":"Ledizioni"},"image":{"@id":"https:\/\/www.ledizioni.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Ledizioni-LediPublishing\/109120559173329","https:\/\/x.com\/ledizioni"]}]}},"cat_url":"https:\/\/www.ledizioni.it\/en\/product-category\/politica\/quaderni-del-master-in-immigrazione\/","_links":{"self":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_cat\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product_cat\/1042"}],"wp:post_type":[{"href":"https:\/\/www.ledizioni.it\/en\/wp-json\/wp\/v2\/product?product_cat=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}